{"id":56,"date":"2023-12-29T15:49:21","date_gmt":"2023-12-29T15:49:21","guid":{"rendered":"https:\/\/redcompafeminista.org\/?page_id=56"},"modified":"2026-09-02T23:05:04","modified_gmt":"2026-09-02T23:05:04","slug":"quienes-somos","status":"publish","type":"page","link":"https:\/\/redcompafeminista.org\/en\/quienes-somos\/","title":{"rendered":"Who we are"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"56\" class=\"elementor elementor-56\" data-elementor-post-type=\"page\">\n\t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-0ed8649 e-con-full e-flex e-con e-parent\" data-id=\"0ed8649\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-72eb46d e-con-full e-flex e-con e-child\" data-id=\"72eb46d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c98ec29 elementor-widget elementor-widget-heading\" data-id=\"c98ec29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfQui\u00e9nes Somos?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bda0310 elementor-widget__width-initial elementor-absolute elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"bda0310\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"606\" height=\"1024\" src=\"https:\/\/redcompafeminista.org\/wp-content\/uploads\/2023\/12\/test_2-510e33de-606x1024.webp\" class=\"attachment-large size-large wp-image-18\" alt=\"\" srcset=\"https:\/\/redcompafeminista.org\/wp-content\/uploads\/2023\/12\/test_2-510e33de-606x1024.webp 606w, https:\/\/redcompafeminista.org\/wp-content\/uploads\/2023\/12\/test_2-510e33de-178x300.webp 178w, https:\/\/redcompafeminista.org\/wp-content\/uploads\/2023\/12\/test_2-510e33de.webp 630w\" sizes=\"(max-width: 606px) 100vw, 606px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-9a7e93c e-con-full e-flex e-con e-child\" data-id=\"9a7e93c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c506fc8 elementor-widget elementor-widget-text-editor\" data-id=\"c506fc8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La Red Compa\u00f1era es un espacio de articulaci\u00f3n regional de organizaciones, redes y colectivas feministas y lesbofeministas que acompa\u00f1amos a mujeres, ni\u00f1as y a otras personas a abortar de manera segura, cuidada y libre de todas las formas de violencias. Somos 27 grupas de 17 pa\u00edses de Am\u00e9rica Latina y El Caribe.<\/p><p>Nuestro modo pol\u00edtico de acompa\u00f1ar abortos es respetando la vida y la salud de las mujeres y personas con capacidad de abortar. Damos respuestas r\u00e1pidas y adecuadas a los diversos contextos de quienes necesitan abortar, tomando en cuenta su experiencia, sus necesidades, con respeto total hac\u00eda sus decisiones, y reconociendo su autonom\u00eda y fortaleza.<\/p><p>Disputamos los saberes de la medicina hegem\u00f3nica colonial y producimos conocimiento entre nosotras\/es, sobre c\u00f3mo acompa\u00f1amos abortos cuidados y feministas.<\/p><p>Nuestro horizonte es la despenalizaci\u00f3n total del aborto, por eso luchamos por el aborto libre, sin causales y sin l\u00edmites de semanas, tambi\u00e9n interpelamos a los Estados para que frenen cualquier intento de persecuci\u00f3n en contra de las\/es acompa\u00f1antes, las mujeres y personas con capacidad de abortar.<\/p><p>Queremos que nunca m\u00e1s abortar se considere un delito.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49a2463 elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"49a2463\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/redcompafeminista.org\/#donde_estamos\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Conoce d\u00f3nde estamos<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-3b9e6fb e-con-full e-flex e-con e-parent\" data-id=\"3b9e6fb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-cb8fc4c e-con-full e-flex e-con e-child\" data-id=\"cb8fc4c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4d52071 elementor-widget elementor-widget-heading\" data-id=\"4d52071\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Misi\u00f3n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b8c2298 elementor-widget elementor-widget-text-editor\" data-id=\"b8c2298\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tNuestra misi\u00f3n es ser un espacio de fortalecimiento, intercambio y articulaci\u00f3n entre las colectivas\/redes\/organizaciones de acompa\u00f1antes de aborto en Am\u00e9rica Latina y El Caribe, para acuerparnos, potenciar y mejorar la manera en que acompa\u00f1amos en aborto con medicamentos y a la vez incidir de manera estrat\u00e9gica en los debates por la despenalizaci\u00f3n\/legalizaci\u00f3n del aborto en cada uno de nuestros territorios.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-3b61bf8 e-con-full e-flex e-con e-child\" data-id=\"3b61bf8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-377a588 elementor-widget elementor-widget-heading\" data-id=\"377a588\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Visi\u00f3n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e25c499 elementor-widget elementor-widget-text-editor\" data-id=\"e25c499\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nuestra visi\u00f3n es que Am\u00e9rica Latina y El Caribe, sea un territorio en d\u00f3nde las mujeres y las personas con capacidad de abortar pueden hacerlo con autonom\u00eda, acompa\u00f1adas por feministas que promueven el aborto libre y acompa\u00f1an desde la justicia social, la felicidad, el placer y el gozo.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74c84d4 elementor-widget__width-initial elementor-absolute elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"74c84d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"197\" height=\"286\" src=\"https:\/\/redcompafeminista.org\/wp-content\/uploads\/2024\/01\/margaritas-feminista.png\" class=\"attachment-large size-large wp-image-3029\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-f71856f e-con-full e-flex e-con e-parent\" data-id=\"f71856f\" data-element_type=\"container\" data-e-type=\"container\" id=\"principios\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-e86302a e-con-full e-flex e-con e-child\" data-id=\"e86302a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-61b0dd4 elementor-widget elementor-widget-heading\" data-id=\"61b0dd4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Principios pol\u00edticos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68951b9 elementor-widget elementor-widget-text-editor\" data-id=\"68951b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La Red Compa\u00f1era debate, dialoga y construye colectivamente los cimientos pol\u00edticos que la sostienen. Los principios que acompa\u00f1an nuestra juntanza y trabajo en red son:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-9953f4b e-flex e-con-boxed e-con e-child\" data-id=\"9953f4b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ef06a75 elementor-widget elementor-widget-toggle\" data-id=\"ef06a75\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2501\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2501\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">1. Acompa\u00f1amos desde el feminismo, sin agregar obst\u00e1culos, causales o plazos<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2501\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2501\"><p>Nos juntan los modos feministas de acompa\u00f1ar y de comprender los abortos, entendiendo las diferentes formas de acompa\u00f1ar que cada grupa que conforma la Red, en cada pa\u00eds va desarrollando.<\/p><p>Acompa\u00f1amos desde el amor y el respeto total hacia la autonom\u00eda de las mujeres y personas con capacidad de abortar, haciendo uso de la escucha activa, sin burocratizar los abortos, es decir, sin causales, sin plazos, sin agregar obst\u00e1culos.<\/p><p>Afirmamos que las mujeres y las personas con capacidad de abortar, son expertas en su vida y son las protagonistas\/es de sus procesos de aborto. Acompa\u00f1amos desde una relaci\u00f3n horizontal, con base en las necesidades de quien abortar\u00e1, reconociendo sus recursos propios y su capacidad de agencia.<\/p><p>Asumimos al aborto como una acci\u00f3n de cuidado de la vida y la salud de las mujeres y personas con capacidad de abortar, como una pr\u00e1ctica cotidiana que buscamos se haga sin miedos, sin culpas, sin dependencias y desde el placer.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2502\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2502\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">2. Entendemos el aborto desde la justicia social, sexual y reproductiva<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2502\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2502\"><p>Reconocemos la experiencia de abortar como una situaci\u00f3n atravesada por las diversas realidades en las que estamos inmersas las mujeres y personas con capacidad de abortar; por lo tanto, entender el aborto desde la justicia social, sexual y reproductiva nos permite acompa\u00f1ar desde una perspectiva interseccional que prioriza las necesidades de aquellas personas pertenecientes a sectores sociales hist\u00f3ricamente minorizados en derechos y\/o en condiciones de vulnerabilidad.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2503\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-2503\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">3. Generamos conocimientos propios y situados en la experiencia de acompa\u00f1ar abortos<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2503\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-2503\"><p>Nos reconocemos, junto con las mujeres y personas con capacidad de abortar que acompa\u00f1amos, como productoras de saberes haciendo teor\u00eda desde la pr\u00e1ctica. Cuestionamos la hegemon\u00eda m\u00e9dica a partir de la informaci\u00f3n que generamos a trav\u00e9s de las experiencias de acompa\u00f1amiento.<\/p><p>Promovemos el derecho a la informaci\u00f3n como una herramienta pol\u00edtica que posibilita el acceso a abortos seguros y prioriza la autonom\u00eda frente a la hegemon\u00eda m\u00e9dica.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2504\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-2504\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">4. Resistimos en colectivo y comunidad al sistema de dominaci\u00f3n y explotaci\u00f3n<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2504\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-2504\"><p>Apostamos a la construcci\u00f3n comunitaria con las mujeres y personas con capacidad de abortar que acompa\u00f1amos. Creemos que la experiencia de abortar se puede vivir en comunidad, el quehacer de la Red fortalece una forma de resistir juntas al sistema de dominaci\u00f3n y explotaci\u00f3n en el que vivimos.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<script type=\"application\/ld+json\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"FAQPage\",\"mainEntity\":[{\"@type\":\"Question\",\"name\":\"1. Acompa\\u00f1amos desde el feminismo, sin agregar obst\\u00e1culos, causales o plazos\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Nos juntan los modos feministas de acompa\\u00f1ar y de comprender los abortos, entendiendo las diferentes formas de acompa\\u00f1ar que cada grupa que conforma la Red, en cada pa\\u00eds va desarrollando.<\\\/p><p>Acompa\\u00f1amos desde el amor y el respeto total hacia la autonom\\u00eda de las mujeres y personas con capacidad de abortar, haciendo uso de la escucha activa, sin burocratizar los abortos, es decir, sin causales, sin plazos, sin agregar obst\\u00e1culos.<\\\/p><p>Afirmamos que las mujeres y las personas con capacidad de abortar, son expertas en su vida y son las protagonistas\\\/es de sus procesos de aborto. Acompa\\u00f1amos desde una relaci\\u00f3n horizontal, con base en las necesidades de quien abortar\\u00e1, reconociendo sus recursos propios y su capacidad de agencia.<\\\/p><p>Asumimos al aborto como una acci\\u00f3n de cuidado de la vida y la salud de las mujeres y personas con capacidad de abortar, como una pr\\u00e1ctica cotidiana que buscamos se haga sin miedos, sin culpas, sin dependencias y desde el placer.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"2. Entendemos el aborto desde la justicia social, sexual y reproductiva\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Reconocemos la experiencia de abortar como una situaci\\u00f3n atravesada por las diversas realidades en las que estamos inmersas las mujeres y personas con capacidad de abortar; por lo tanto, entender el aborto desde la justicia social, sexual y reproductiva nos permite acompa\\u00f1ar desde una perspectiva interseccional que prioriza las necesidades de aquellas personas pertenecientes a sectores sociales hist\\u00f3ricamente minorizados en derechos y\\\/o en condiciones de vulnerabilidad.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"3. Generamos conocimientos propios y situados en la experiencia de acompa\\u00f1ar abortos\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Nos reconocemos, junto con las mujeres y personas con capacidad de abortar que acompa\\u00f1amos, como productoras de saberes haciendo teor\\u00eda desde la pr\\u00e1ctica. Cuestionamos la hegemon\\u00eda m\\u00e9dica a partir de la informaci\\u00f3n que generamos a trav\\u00e9s de las experiencias de acompa\\u00f1amiento.<\\\/p><p>Promovemos el derecho a la informaci\\u00f3n como una herramienta pol\\u00edtica que posibilita el acceso a abortos seguros y prioriza la autonom\\u00eda frente a la hegemon\\u00eda m\\u00e9dica.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"4. Resistimos en colectivo y comunidad al sistema de dominaci\\u00f3n y explotaci\\u00f3n\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Apostamos a la construcci\\u00f3n comunitaria con las mujeres y personas con capacidad de abortar que acompa\\u00f1amos. Creemos que la experiencia de abortar se puede vivir en comunidad, el quehacer de la Red fortalece una forma de resistir juntas al sistema de dominaci\\u00f3n y explotaci\\u00f3n en el que vivimos.<\\\/p>\"}}]}<\/script>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-cb36021 e-con-full e-flex e-con e-parent\" data-id=\"cb36021\" data-element_type=\"container\" data-e-type=\"container\" id=\"historia\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-c2c42ba e-flex e-con-boxed e-con e-child\" data-id=\"c2c42ba\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-21a1c16 elementor-widget__width-initial elementor-absolute elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"21a1c16\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"516\" height=\"756\" src=\"https:\/\/redcompafeminista.org\/wp-content\/uploads\/2023\/12\/red-companera-feminismo.webp\" class=\"attachment-large size-large wp-image-41\" alt=\"\" srcset=\"https:\/\/redcompafeminista.org\/wp-content\/uploads\/2023\/12\/red-companera-feminismo.webp 516w, https:\/\/redcompafeminista.org\/wp-content\/uploads\/2023\/12\/red-companera-feminismo-205x300.webp 205w\" sizes=\"(max-width: 516px) 100vw, 516px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a3f474a elementor-widget elementor-widget-heading\" data-id=\"a3f474a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nuestra historia<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-07b6355 elementor-widget elementor-widget-text-editor\" data-id=\"07b6355\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La Red Compa\u00f1era viene de un proceso de encuentros y complicidades feministas. Nos encontramos desde todos los rincones de la regi\u00f3n y conjugamos nuestras diversas y complejas maneras de estar y hacer feminismo. Nos junta el acompa\u00f1ar abortos, nos juntan las ganas de cambiarlo todo.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-317d781 elementor-widget elementor-widget-qi_addons_for_elementor_timeline\" data-id=\"317d781\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_timeline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-timeline qodef-timeline--vertical qodef-timeline-layout--vertical-separated qodef-line--outside qodef-point--standard qodef-qi--has-appear qodef-reverse-padding\">\n\t<div class=\"qodef-e qodef-e-item elementor-repeater-item-966ae7f qodef-obverse\">\n\t<div class=\"qodef-e-line-holder\">\n\t\t<span class=\"qodef-e-line\"><\/span>\n\t<\/div>\n\t<div class=\"qodef-e-item-inner\">\n\t\t<div class=\"qodef-e-point-holder\">\n\t\t\t<div class=\"qodef-e-point\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"qodef-e-side-holder\">\n\t\t\t<div class=\"qodef-e-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/redcompafeminista.org\/wp-content\/uploads\/2024\/01\/encuentro_lima_2020_1-300x200.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/redcompafeminista.org\/wp-content\/uploads\/2024\/01\/encuentro_lima_2020_1-300x200.png 300w, https:\/\/redcompafeminista.org\/wp-content\/uploads\/2024\/01\/encuentro_lima_2020_1-768x512.png 768w, https:\/\/redcompafeminista.org\/wp-content\/uploads\/2024\/01\/encuentro_lima_2020_1.png 900w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/div>\n\t\t<div class=\"qodef-e-content-holder\">\n\t\t\t\t<div class=\"qodef-e-date\">\n\t\tMarzo del 2017\t<\/div>\n\t\t\t\t\t<h2 class=\"qodef-e-title\">\n\t\tNos Conocimos\t\t<\/h2>\n\t\t\t\t\t<p class=\"qodef-e-text\">\n\t\tEn Ecuador se realiza una primera reuni\u00f3n de l\u00edneas y redes de acompa\u00f1antes de la regi\u00f3n. En esta reuni\u00f3n nos encontramos varias grupas de acompa\u00f1antes por primera vez, fue el espacio en el que nos conocimos y reconocimos, y empezamos a pensar en la posibilidad de agruparnos y juntarnos regionalmente.\t<\/p>\n\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-e-item elementor-repeater-item-71fa44e qodef-reverse\">\n\t<div class=\"qodef-e-line-holder\">\n\t\t<span class=\"qodef-e-line\"><\/span>\n\t<\/div>\n\t<div class=\"qodef-e-item-inner\">\n\t\t<div class=\"qodef-e-point-holder\">\n\t\t\t<div class=\"qodef-e-point\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"qodef-e-side-holder\">\n\t\t\t<div class=\"qodef-e-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/redcompafeminista.org\/wp-content\/uploads\/2024\/01\/eflac-300x200.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/redcompafeminista.org\/wp-content\/uploads\/2024\/01\/eflac-300x200.png 300w, https:\/\/redcompafeminista.org\/wp-content\/uploads\/2024\/01\/eflac-768x512.png 768w, https:\/\/redcompafeminista.org\/wp-content\/uploads\/2024\/01\/eflac.png 900w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/div>\n\t\t<div class=\"qodef-e-content-holder\">\n\t\t\t\t<div class=\"qodef-e-date\">\n\t\tNoviembre del 2017\t<\/div>\n\t\t\t\t\t<h2 class=\"qodef-e-title\">\n\t\tXIV EFLAC, Montevideo, Uruguay\t\t<\/h2>\n\t\t\t\t\t<p class=\"qodef-e-text\">\n\t\tDurante el 14 Encuentro Feminista Latinoamericano y de El Caribe, en un espacio convocado por fuera del programa oficial, acompa\u00f1antes de aborto de Chile, Argentina y Brasil, reafirmaron la importancia de la vinculaci\u00f3n entre grupas, as\u00ed como la posibilidad de realizar una reuni\u00f3n que convocara a grupas de acompa\u00f1antes de aborto de toda la regi\u00f3n.\t<\/p>\n\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-e-item elementor-repeater-item-57e684c qodef-obverse\">\n\t<div class=\"qodef-e-line-holder\">\n\t\t<span class=\"qodef-e-line\"><\/span>\n\t<\/div>\n\t<div class=\"qodef-e-item-inner\">\n\t\t<div class=\"qodef-e-point-holder\">\n\t\t\t<div class=\"qodef-e-point\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"qodef-e-side-holder\">\n\t\t\t<div class=\"qodef-e-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/redcompafeminista.org\/wp-content\/uploads\/2024\/01\/encuentro_bali-300x200.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/redcompafeminista.org\/wp-content\/uploads\/2024\/01\/encuentro_bali-300x200.png 300w, https:\/\/redcompafeminista.org\/wp-content\/uploads\/2024\/01\/encuentro_bali-768x512.png 768w, https:\/\/redcompafeminista.org\/wp-content\/uploads\/2024\/01\/encuentro_bali.png 900w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/div>\n\t\t<div class=\"qodef-e-content-holder\">\n\t\t\t\t<div class=\"qodef-e-date\">\n\t\tJulio del 2018\t<\/div>\n\t\t\t\t\t<h2 class=\"qodef-e-title\">\n\t\tSegunda Reuni\u00f3n Global de L\u00edneas Telef\u00f3nicas de Aborto Seguro\t\t<\/h2>\n\t\t\t\t\t<p class=\"qodef-e-text\">\n\t\tSamsara, Ibis Reproductive Health y Women Help Women convocan a la Segunda Reuni\u00f3n Global de L\u00edneas Telef\u00f3nicas de Aborto Seguro (Global Hotline Meeting, o GHM) en Bali, Indonesia. En esa reuni\u00f3n coincidimos varias organizaciones de acompa\u00f1antes de Am\u00e9rica Latina y decidimos hacer un primer encuentro de grupas de acompa\u00f1antes de la Am\u00e9rica Latina y el Caribe, para generar una red regional de acompa\u00f1antes.\t<\/p>\n\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-e-item elementor-repeater-item-7757059 qodef-reverse\">\n\t<div class=\"qodef-e-line-holder\">\n\t\t<span class=\"qodef-e-line\"><\/span>\n\t<\/div>\n\t<div class=\"qodef-e-item-inner\">\n\t\t<div class=\"qodef-e-point-holder\">\n\t\t\t<div class=\"qodef-e-point\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"qodef-e-side-holder\">\n\t\t\t<div class=\"qodef-e-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/redcompafeminista.org\/wp-content\/uploads\/2024\/01\/encuentro_chile-300x200.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/redcompafeminista.org\/wp-content\/uploads\/2024\/01\/encuentro_chile-300x200.png 300w, https:\/\/redcompafeminista.org\/wp-content\/uploads\/2024\/01\/encuentro_chile-768x512.png 768w, https:\/\/redcompafeminista.org\/wp-content\/uploads\/2024\/01\/encuentro_chile.png 900w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/div>\n\t\t<div class=\"qodef-e-content-holder\">\n\t\t\t\t<div class=\"qodef-e-date\">\n\t\tSeptiembre de 2018\t<\/div>\n\t\t\t\t\t<h2 class=\"qodef-e-title\">\n\t\t1er Encuentro de la Red Feminista Latinoamericana y Caribe\u00f1a de Acompa\u00f1antes de Aborto\t\t<\/h2>\n\t\t\t\t\t<p class=\"qodef-e-text\">\n\t\tNos juntamos en Chile para materializar nuestros sue\u00f1os, en esta reuni\u00f3n decidimos conformar la Red Feminista Latinoamericana y Caribe\u00f1a de acompa\u00f1antes de abortos.\t<\/p>\n\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-e-item elementor-repeater-item-b82df6c qodef-obverse\">\n\t<div class=\"qodef-e-line-holder\">\n\t\t<span class=\"qodef-e-line\"><\/span>\n\t<\/div>\n\t<div class=\"qodef-e-item-inner\">\n\t\t<div class=\"qodef-e-point-holder\">\n\t\t\t<div class=\"qodef-e-point\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"qodef-e-side-holder\">\n\t\t\t<div class=\"qodef-e-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/redcompafeminista.org\/wp-content\/uploads\/2024\/01\/encuentro_lima_2020_2-300x200.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/redcompafeminista.org\/wp-content\/uploads\/2024\/01\/encuentro_lima_2020_2-300x200.png 300w, https:\/\/redcompafeminista.org\/wp-content\/uploads\/2024\/01\/encuentro_lima_2020_2-768x512.png 768w, https:\/\/redcompafeminista.org\/wp-content\/uploads\/2024\/01\/encuentro_lima_2020_2.png 900w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/div>\n\t\t<div class=\"qodef-e-content-holder\">\n\t\t\t\t<div class=\"qodef-e-date\">\n\t\tEnero de 2020\t<\/div>\n\t\t\t\t\t<h2 class=\"qodef-e-title\">\n\t\t2do Encuentro de la Red Feminista Latinoamericana y Caribe\u00f1a de Acompa\u00f1antes de Aborto\t\t<\/h2>\n\t\t\t\t\t<p class=\"qodef-e-text\">\n\t\tNos reunimos en Lima-Per\u00fa, para construir colectivamente nuestra misi\u00f3n, visi\u00f3n, principios y prioridades que definen nuestras acciones futuras. En este encuentro la Red qued\u00f3 conformada por 21 grupas, de 15 pa\u00edses. Esperamos que m\u00e1s grupas de acompa\u00f1antes se sumen en el camino.\t<\/p>\n\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-e-item elementor-repeater-item-58b530d qodef-reverse\">\n\t<div class=\"qodef-e-line-holder\">\n\t\t<span class=\"qodef-e-line\"><\/span>\n\t<\/div>\n\t<div class=\"qodef-e-item-inner\">\n\t\t<div class=\"qodef-e-point-holder\">\n\t\t\t<div class=\"qodef-e-point\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"qodef-e-side-holder\">\n\t\t\t<div class=\"qodef-e-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/redcompafeminista.org\/wp-content\/uploads\/2024\/01\/red-300x200.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/redcompafeminista.org\/wp-content\/uploads\/2024\/01\/red-300x200.png 300w, https:\/\/redcompafeminista.org\/wp-content\/uploads\/2024\/01\/red-768x512.png 768w, https:\/\/redcompafeminista.org\/wp-content\/uploads\/2024\/01\/red.png 900w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/div>\n\t\t<div class=\"qodef-e-content-holder\">\n\t\t\t\t<div class=\"qodef-e-date\">\n\t\tA inicios del 2021\t<\/div>\n\t\t\t\t\t<h2 class=\"qodef-e-title\">\n\t\tGeneramos una identidad colectiva\t\t<\/h2>\n\t\t\t\t\t<p class=\"qodef-e-text\">\n\t\tLa Red logra tener una identidad colectiva. Nombrarnos como Red Compa\u00f1era significa acompa\u00f1arnos entre todas y abrazar la vida, somos c\u00f3mplices entre amigas y desconocidas, de un hemisferio a otro, somos compa\u00f1eras.\t<\/p>\n\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u00bfQui\u00e9nes Somos? La Red Compa\u00f1era es un espacio de articulaci\u00f3n regional de organizaciones, redes y colectivas feministas y lesbofeministas que acompa\u00f1amos a mujeres, ni\u00f1as y a otras personas a abortar de manera segura, cuidada y libre de todas las formas de violencias. Somos 27 grupas de 17 pa\u00edses de Am\u00e9rica Latina y El Caribe. Nuestro [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-56","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/redcompafeminista.org\/en\/wp-json\/wp\/v2\/pages\/56","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redcompafeminista.org\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/redcompafeminista.org\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/redcompafeminista.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/redcompafeminista.org\/en\/wp-json\/wp\/v2\/comments?post=56"}],"version-history":[{"count":106,"href":"https:\/\/redcompafeminista.org\/en\/wp-json\/wp\/v2\/pages\/56\/revisions"}],"predecessor-version":[{"id":4216,"href":"https:\/\/redcompafeminista.org\/en\/wp-json\/wp\/v2\/pages\/56\/revisions\/4216"}],"wp:attachment":[{"href":"https:\/\/redcompafeminista.org\/en\/wp-json\/wp\/v2\/media?parent=56"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}